{"id":35377,"date":"2024-03-14T18:45:35","date_gmt":"2024-03-14T17:45:35","guid":{"rendered":"https:\/\/www.pleteninespenko.si\/?post_type=product&#038;p=35377"},"modified":"2026-09-02T02:10:23","modified_gmt":"2026-09-02T00:10:23","slug":"strickjacke-diona","status":"publish","type":"product","link":"https:\/\/www.pleteninespenko.si\/de\/handel\/damenstrickwaren\/strickjacken-fur-damen\/strickjacke-diona\/","title":{"rendered":"Strickjacke Diona"},"content":{"rendered":"<div><span style=\"color: #9655a2;\"><strong>Material:<\/strong><\/span><br \/>\n50 % Baumwolle<br \/>\n50 % Acryl<\/div>\n<p>&nbsp;<\/p>\n<div>Falls Sie Ihre Gr\u00f6\u00dfe oder Farbe nicht finden, kontaktieren Sie uns per E-Mail <b><a href=\"mailto:info@pleteninespenko.si\" target=\"_blank\" rel=\"noopener noreferrer\">info@pleteninespenko.si<\/a><\/b> oder unter der Nummer <b><a href=\"tel:+386%201%20834%2015%2023\" target=\"_blank\" rel=\"noopener noreferrer\">01 834 15 23<\/a><\/b> oder <b><a href=\"tel:+386%2051%20304%20660\" target=\"_blank\" rel=\"noopener noreferrer\">051 304 660<\/a><\/b> &#8211; wir beraten Sie gerne Slowenisches Produkt, hergestellt in unserer Handwerkswerstatt in Komenda<\/div>\n<p>&nbsp;<\/p>\n<div>Erh\u00e4tlich in allen Gesch\u00e4ften <b><a href=\"https:\/\/www.pleteninespenko.si\/de\/wo-sind-wir\/\" target=\"_blank\" rel=\"noopener\"> in Slowenien und Kroatien<\/a><\/b>.<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Strickjacke aus Baumwolle mit Taschen, Rei\u00dfverschluss, hohem Kragen und Streifen an Kragen, Schultern und Taschen. Es kann mit dem Beslinda-Pullover und Minirock oder mit einer klassischen Hose kombiniert werden.<\/p>\n<p><strong><a href=\"https:\/\/www.pleteninespenko.si\/de\/geschaftsbedingungen\/#messungen\" target=\"_blank\" rel=\"noopener noreferrer\"> Denken Sie daran, sich selbst zu messen &gt;<\/a><\/strong><\/p>\n","protected":false},"featured_media":34834,"comment_status":"open","ping_status":"closed","template":"","meta":{"inline_featured_image":false},"pwb-brand":[2138],"product_brand":[],"product_cat":[2540,2732],"product_tag":[2921,1840],"class_list":["post-35377","product","type-product","status-publish","has-post-thumbnail","pwb-brand-eigenproduktion","product_cat-damenstrickwaren","product_cat-strickjacken-fur-damen","product_tag-acryl","product_tag-baumwolle","has-post-title","has-post-date","has-post-category","has-post-tag","has-post-comment","has-post-author","","first","instock","taxable","shipping-taxable","purchasable","product-type-variable"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Strickjacke Diona | Pletenine \u0160penko<\/title>\n<meta name=\"description\" content=\"Strickjacke aus Baumwolle mit Taschen, Rei\u00dfverschluss, hohem Kragen und Streifen an Kragen, Schultern und Taschen. Es kann mit dem Beslinda-Pullover und Minirock oder mit einer klassischen Hose kombiniert werden.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.pleteninespenko.si\/de\/handel\/damenstrickwaren\/strickjacken-fur-damen\/strickjacke-diona\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Strickjacke Diona | Pletenine \u0160penko\" \/>\n<meta property=\"og:description\" content=\"Strickjacke aus Baumwolle mit Taschen, Rei\u00dfverschluss, hohem Kragen und Streifen an Kragen, Schultern und Taschen. Es kann mit dem Beslinda-Pullover und Minirock oder mit einer klassischen Hose kombiniert werden.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.pleteninespenko.si\/de\/handel\/damenstrickwaren\/strickjacken-fur-damen\/strickjacke-diona\/\" \/>\n<meta property=\"og:site_name\" content=\"Pletenine \u0160penko\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/PletenineSpenko\/\" \/>\n<meta property=\"article:modified_time\" content=\"2026-09-02T00:10:23+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.pleteninespenko.si\/wp-content\/uploads\/2024\/03\/Pletenine_Spenko_zenske_pletenine_jopica-diona-modra.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"1324\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"1\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.pleteninespenko.si\\\/de\\\/handel\\\/damenstrickwaren\\\/strickjacken-fur-damen\\\/strickjacke-diona\\\/\",\"url\":\"https:\\\/\\\/www.pleteninespenko.si\\\/de\\\/handel\\\/damenstrickwaren\\\/strickjacken-fur-damen\\\/strickjacke-diona\\\/\",\"name\":\"Strickjacke Diona | Pletenine \u0160penko\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.pleteninespenko.si\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.pleteninespenko.si\\\/de\\\/handel\\\/damenstrickwaren\\\/strickjacken-fur-damen\\\/strickjacke-diona\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.pleteninespenko.si\\\/de\\\/handel\\\/damenstrickwaren\\\/strickjacken-fur-damen\\\/strickjacke-diona\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.pleteninespenko.si\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/Pletenine_Spenko_zenske_pletenine_jopica-diona-modra.jpg\",\"datePublished\":\"2024-03-14T17:45:35+00:00\",\"dateModified\":\"2026-09-02T00:10:23+00:00\",\"description\":\"Strickjacke aus Baumwolle mit Taschen, Rei\u00dfverschluss, hohem Kragen und Streifen an Kragen, Schultern und Taschen. Es kann mit dem Beslinda-Pullover und Minirock oder mit einer klassischen Hose kombiniert werden.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.pleteninespenko.si\\\/de\\\/handel\\\/damenstrickwaren\\\/strickjacken-fur-damen\\\/strickjacke-diona\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.pleteninespenko.si\\\/de\\\/handel\\\/damenstrickwaren\\\/strickjacken-fur-damen\\\/strickjacke-diona\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.pleteninespenko.si\\\/de\\\/handel\\\/damenstrickwaren\\\/strickjacken-fur-damen\\\/strickjacke-diona\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.pleteninespenko.si\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/Pletenine_Spenko_zenske_pletenine_jopica-diona-modra.jpg\",\"contentUrl\":\"https:\\\/\\\/www.pleteninespenko.si\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/Pletenine_Spenko_zenske_pletenine_jopica-diona-modra.jpg\",\"width\":1200,\"height\":1324,\"caption\":\"Strickjacke aus Baumwolle mit Taschen, Rei\u00dfverschluss, hohem Kragen und Streifen an Kragen, Schultern und Taschen. Es kann mit dem Beslinda-Pullover und Minirock oder mit einer klassischen Hose kombiniert werden.\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.pleteninespenko.si\\\/de\\\/handel\\\/damenstrickwaren\\\/strickjacken-fur-damen\\\/strickjacke-diona\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.pleteninespenko.si\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Handel\",\"item\":\"https:\\\/\\\/www.pleteninespenko.si\\\/de\\\/handel\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Strickjacke Diona\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.pleteninespenko.si\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/www.pleteninespenko.si\\\/de\\\/\",\"name\":\"Pletenine \u0160penko\",\"description\":\"Damen- und Herrenstrickwaren nach der neuesten Mode\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.pleteninespenko.si\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.pleteninespenko.si\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.pleteninespenko.si\\\/de\\\/#organization\",\"name\":\"Pletenine \u0160penko\",\"url\":\"https:\\\/\\\/www.pleteninespenko.si\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.pleteninespenko.si\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.pleteninespenko.si\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/Pletenine_Spenko.png\",\"contentUrl\":\"https:\\\/\\\/www.pleteninespenko.si\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/Pletenine_Spenko.png\",\"width\":717,\"height\":140,\"caption\":\"Pletenine \u0160penko\"},\"image\":{\"@id\":\"https:\\\/\\\/www.pleteninespenko.si\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/PletenineSpenko\\\/\",\"https:\\\/\\\/www.instagram.com\\\/pleteninespenko\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Strickjacke Diona | Pletenine \u0160penko","description":"Strickjacke aus Baumwolle mit Taschen, Rei\u00dfverschluss, hohem Kragen und Streifen an Kragen, Schultern und Taschen. Es kann mit dem Beslinda-Pullover und Minirock oder mit einer klassischen Hose kombiniert werden.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.pleteninespenko.si\/de\/handel\/damenstrickwaren\/strickjacken-fur-damen\/strickjacke-diona\/","og_locale":"de_DE","og_type":"article","og_title":"Strickjacke Diona | Pletenine \u0160penko","og_description":"Strickjacke aus Baumwolle mit Taschen, Rei\u00dfverschluss, hohem Kragen und Streifen an Kragen, Schultern und Taschen. Es kann mit dem Beslinda-Pullover und Minirock oder mit einer klassischen Hose kombiniert werden.","og_url":"https:\/\/www.pleteninespenko.si\/de\/handel\/damenstrickwaren\/strickjacken-fur-damen\/strickjacke-diona\/","og_site_name":"Pletenine \u0160penko","article_publisher":"https:\/\/www.facebook.com\/PletenineSpenko\/","article_modified_time":"2026-09-02T00:10:23+00:00","og_image":[{"width":1200,"height":1324,"url":"https:\/\/www.pleteninespenko.si\/wp-content\/uploads\/2024\/03\/Pletenine_Spenko_zenske_pletenine_jopica-diona-modra.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"1\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.pleteninespenko.si\/de\/handel\/damenstrickwaren\/strickjacken-fur-damen\/strickjacke-diona\/","url":"https:\/\/www.pleteninespenko.si\/de\/handel\/damenstrickwaren\/strickjacken-fur-damen\/strickjacke-diona\/","name":"Strickjacke Diona | Pletenine \u0160penko","isPartOf":{"@id":"https:\/\/www.pleteninespenko.si\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.pleteninespenko.si\/de\/handel\/damenstrickwaren\/strickjacken-fur-damen\/strickjacke-diona\/#primaryimage"},"image":{"@id":"https:\/\/www.pleteninespenko.si\/de\/handel\/damenstrickwaren\/strickjacken-fur-damen\/strickjacke-diona\/#primaryimage"},"thumbnailUrl":"https:\/\/www.pleteninespenko.si\/wp-content\/uploads\/2024\/03\/Pletenine_Spenko_zenske_pletenine_jopica-diona-modra.jpg","datePublished":"2024-03-14T17:45:35+00:00","dateModified":"2026-09-02T00:10:23+00:00","description":"Strickjacke aus Baumwolle mit Taschen, Rei\u00dfverschluss, hohem Kragen und Streifen an Kragen, Schultern und Taschen. Es kann mit dem Beslinda-Pullover und Minirock oder mit einer klassischen Hose kombiniert werden.","breadcrumb":{"@id":"https:\/\/www.pleteninespenko.si\/de\/handel\/damenstrickwaren\/strickjacken-fur-damen\/strickjacke-diona\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.pleteninespenko.si\/de\/handel\/damenstrickwaren\/strickjacken-fur-damen\/strickjacke-diona\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.pleteninespenko.si\/de\/handel\/damenstrickwaren\/strickjacken-fur-damen\/strickjacke-diona\/#primaryimage","url":"https:\/\/www.pleteninespenko.si\/wp-content\/uploads\/2024\/03\/Pletenine_Spenko_zenske_pletenine_jopica-diona-modra.jpg","contentUrl":"https:\/\/www.pleteninespenko.si\/wp-content\/uploads\/2024\/03\/Pletenine_Spenko_zenske_pletenine_jopica-diona-modra.jpg","width":1200,"height":1324,"caption":"Strickjacke aus Baumwolle mit Taschen, Rei\u00dfverschluss, hohem Kragen und Streifen an Kragen, Schultern und Taschen. Es kann mit dem Beslinda-Pullover und Minirock oder mit einer klassischen Hose kombiniert werden."},{"@type":"BreadcrumbList","@id":"https:\/\/www.pleteninespenko.si\/de\/handel\/damenstrickwaren\/strickjacken-fur-damen\/strickjacke-diona\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.pleteninespenko.si\/de\/"},{"@type":"ListItem","position":2,"name":"Handel","item":"https:\/\/www.pleteninespenko.si\/de\/handel\/"},{"@type":"ListItem","position":3,"name":"Strickjacke Diona"}]},{"@type":"WebSite","@id":"https:\/\/www.pleteninespenko.si\/de\/#website","url":"https:\/\/www.pleteninespenko.si\/de\/","name":"Pletenine \u0160penko","description":"Damen- und Herrenstrickwaren nach der neuesten Mode","publisher":{"@id":"https:\/\/www.pleteninespenko.si\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.pleteninespenko.si\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.pleteninespenko.si\/de\/#organization","name":"Pletenine \u0160penko","url":"https:\/\/www.pleteninespenko.si\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.pleteninespenko.si\/de\/#\/schema\/logo\/image\/","url":"https:\/\/www.pleteninespenko.si\/wp-content\/uploads\/2020\/06\/Pletenine_Spenko.png","contentUrl":"https:\/\/www.pleteninespenko.si\/wp-content\/uploads\/2020\/06\/Pletenine_Spenko.png","width":717,"height":140,"caption":"Pletenine \u0160penko"},"image":{"@id":"https:\/\/www.pleteninespenko.si\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/PletenineSpenko\/","https:\/\/www.instagram.com\/pleteninespenko\/"]}]}},"brands":[{"id":2138,"name":"Eigenproduktion","slug":"eigenproduktion"}],"_links":{"self":[{"href":"https:\/\/www.pleteninespenko.si\/de\/wp-json\/wp\/v2\/product\/35377","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.pleteninespenko.si\/de\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.pleteninespenko.si\/de\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/www.pleteninespenko.si\/de\/wp-json\/wp\/v2\/comments?post=35377"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.pleteninespenko.si\/de\/wp-json\/wp\/v2\/media\/34834"}],"wp:attachment":[{"href":"https:\/\/www.pleteninespenko.si\/de\/wp-json\/wp\/v2\/media?parent=35377"}],"wp:term":[{"taxonomy":"pwb-brand","embeddable":true,"href":"https:\/\/www.pleteninespenko.si\/de\/wp-json\/wp\/v2\/pwb-brand?post=35377"},{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.pleteninespenko.si\/de\/wp-json\/wp\/v2\/product_brand?post=35377"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.pleteninespenko.si\/de\/wp-json\/wp\/v2\/product_cat?post=35377"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.pleteninespenko.si\/de\/wp-json\/wp\/v2\/product_tag?post=35377"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}