{"id":28267,"date":"2023-06-02T21:00:58","date_gmt":"2023-06-02T19:00:58","guid":{"rendered":"https:\/\/www.pleteninespenko.si\/?post_type=product&#038;p=28267"},"modified":"2026-09-02T02:10:20","modified_gmt":"2026-09-02T00:10:20","slug":"dzemper-dalida","status":"publish","type":"product","link":"https:\/\/www.pleteninespenko.si\/hr\/trgovina\/zenska-pletenina\/zenski-dzemperi\/dzemper-dalida\/","title":{"rendered":"D\u017eemper Dalida"},"content":{"rendered":"<div><span style=\"color: #9655a2;\"><strong>Sastav:<\/strong><\/span><br \/>\n50 % pamuk<br \/>\n50 % akril<\/div>\n<p>&nbsp;<\/p>\n<div>U slu\u010daju da ne prona\u0111ete svoju veli\u010dinu ili boju, kontaktirajte nas putem e-po\u0161te <b><a href=\"mailto:info@pleteninespenko.si\" target=\"_blank\" rel=\"noopener noreferrer\">info@pleteninespenko.si<\/a><\/b> ili na broj <b><a href=\"tel:+386%201%20834%2015%2023\" target=\"_blank\" rel=\"noopener noreferrer\">01 834 15 23<\/a><\/b> ili <b><a href=\"tel:+386%2051%20304%20660\" target=\"_blank\" rel=\"noopener noreferrer\">051 304 660<\/a><\/b> &#8211; rado \u0107emo vam savjetovati. Slovenski proizvod, napravljeno u na\u0161oj obrtni\u010dki radionici u Komendi.<\/div>\n<p>&nbsp;<\/p>\n<div>Dostupno u svim trgovinama u <b><a href=\"https:\/\/www.pleteninespenko.si\/hr\/gdje-se-nalazimo\/\" target=\"_blank\" rel=\"noopener\"> Sloveniji i u Hrvatskoj<\/a><\/b>.<\/div>\n","protected":false},"excerpt":{"rendered":"<p>D\u017eemper mornarskog izgleda s patentiranim V izrezom, na rukavima i donjem dijelu. Uzorak pruga u boji upotpunjuje izgled d\u017eempera. Nezamjenjiv u hladnim ljetnim ve\u010derima.<\/p>\n<p><strong><a href=\"https:\/\/www.pleteninespenko.si\/hr\/opci-uvjeti\/#mjere\" target=\"_blank\" rel=\"noopener noreferrer\"> Ne zaboravite se izmjeriti &gt;<\/a><\/strong><\/p>\n","protected":false},"featured_media":28307,"comment_status":"open","ping_status":"closed","template":"","meta":{"inline_featured_image":false},"pwb-brand":[2137],"product_brand":[],"product_cat":[1813,2757],"product_tag":[1820],"class_list":["post-28267","product","type-product","status-publish","has-post-thumbnail","pwb-brand-vlastita-proizvodnja","product_cat-zenska-pletenina","product_cat-zenski-dzemperi","product_tag-pamuk","has-post-title","has-post-date","has-post-category","has-post-tag","has-post-comment","has-post-author","","first","instock","taxable","shipping-taxable","purchasable","product-type-variable"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>D\u017eemper Dalida | Pletenine \u0160penko<\/title>\n<meta name=\"description\" content=\"D\u017eemper mornarskog izgleda s patentiranim V izrezom, na rukavima i donjem dijelu. Uzorak pruga u boji upotpunjuje izgled d\u017eempera. Nezamjenjiv u hladnim ljetnim ve\u010derima.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.pleteninespenko.si\/hr\/trgovina\/zenska-pletenina\/zenski-dzemperi\/dzemper-dalida\/\" \/>\n<meta property=\"og:locale\" content=\"hr_HR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"D\u017eemper Dalida | Pletenine \u0160penko\" \/>\n<meta property=\"og:description\" content=\"D\u017eemper mornarskog izgleda s patentiranim V izrezom, na rukavima i donjem dijelu. Uzorak pruga u boji upotpunjuje izgled d\u017eempera. Nezamjenjiv u hladnim ljetnim ve\u010derima.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.pleteninespenko.si\/hr\/trgovina\/zenska-pletenina\/zenski-dzemperi\/dzemper-dalida\/\" \/>\n<meta property=\"og:site_name\" content=\"Pletenine \u0160penko\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/PletenineSpenko\/\" \/>\n<meta property=\"article:modified_time\" content=\"2026-09-02T00:10:20+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.pleteninespenko.si\/wp-content\/uploads\/2023\/06\/Pletenine_Spenko_pulover-Dalida-bel.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"1324\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Procijenjeno vrijeme \u010ditanja\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuta\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.pleteninespenko.si\\\/hr\\\/trgovina\\\/zenska-pletenina\\\/zenski-dzemperi\\\/dzemper-dalida\\\/\",\"url\":\"https:\\\/\\\/www.pleteninespenko.si\\\/hr\\\/trgovina\\\/zenska-pletenina\\\/zenski-dzemperi\\\/dzemper-dalida\\\/\",\"name\":\"D\u017eemper Dalida | Pletenine \u0160penko\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.pleteninespenko.si\\\/hr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.pleteninespenko.si\\\/hr\\\/trgovina\\\/zenska-pletenina\\\/zenski-dzemperi\\\/dzemper-dalida\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.pleteninespenko.si\\\/hr\\\/trgovina\\\/zenska-pletenina\\\/zenski-dzemperi\\\/dzemper-dalida\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.pleteninespenko.si\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/Pletenine_Spenko_pulover-Dalida-bel.jpg\",\"datePublished\":\"2023-06-02T19:00:58+00:00\",\"dateModified\":\"2026-09-02T00:10:20+00:00\",\"description\":\"D\u017eemper mornarskog izgleda s patentiranim V izrezom, na rukavima i donjem dijelu. Uzorak pruga u boji upotpunjuje izgled d\u017eempera. Nezamjenjiv u hladnim ljetnim ve\u010derima.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.pleteninespenko.si\\\/hr\\\/trgovina\\\/zenska-pletenina\\\/zenski-dzemperi\\\/dzemper-dalida\\\/#breadcrumb\"},\"inLanguage\":\"hr\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.pleteninespenko.si\\\/hr\\\/trgovina\\\/zenska-pletenina\\\/zenski-dzemperi\\\/dzemper-dalida\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"hr\",\"@id\":\"https:\\\/\\\/www.pleteninespenko.si\\\/hr\\\/trgovina\\\/zenska-pletenina\\\/zenski-dzemperi\\\/dzemper-dalida\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.pleteninespenko.si\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/Pletenine_Spenko_pulover-Dalida-bel.jpg\",\"contentUrl\":\"https:\\\/\\\/www.pleteninespenko.si\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/Pletenine_Spenko_pulover-Dalida-bel.jpg\",\"width\":1200,\"height\":1324,\"caption\":\"D\u017eemper mornarskog izgleda s patentiranim V izrezom, na rukavima i donjem dijelu. Uzorak pruga u boji upotpunjuje izgled d\u017eempera. Nezamjenjiv u hladnim ljetnim ve\u010derima.\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.pleteninespenko.si\\\/hr\\\/trgovina\\\/zenska-pletenina\\\/zenski-dzemperi\\\/dzemper-dalida\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.pleteninespenko.si\\\/hr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Trgovina\",\"item\":\"https:\\\/\\\/www.pleteninespenko.si\\\/hr\\\/trgovina\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"D\u017eemper Dalida\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.pleteninespenko.si\\\/hr\\\/#website\",\"url\":\"https:\\\/\\\/www.pleteninespenko.si\\\/hr\\\/\",\"name\":\"Pletenine \u0160penko\",\"description\":\"\u017denska i mu\u0161ka trikota\u017ea po posljednjoj modi\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.pleteninespenko.si\\\/hr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.pleteninespenko.si\\\/hr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"hr\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.pleteninespenko.si\\\/hr\\\/#organization\",\"name\":\"Pletenine \u0160penko\",\"url\":\"https:\\\/\\\/www.pleteninespenko.si\\\/hr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"hr\",\"@id\":\"https:\\\/\\\/www.pleteninespenko.si\\\/hr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.pleteninespenko.si\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/Pletenine_Spenko.png\",\"contentUrl\":\"https:\\\/\\\/www.pleteninespenko.si\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/Pletenine_Spenko.png\",\"width\":717,\"height\":140,\"caption\":\"Pletenine \u0160penko\"},\"image\":{\"@id\":\"https:\\\/\\\/www.pleteninespenko.si\\\/hr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/PletenineSpenko\\\/\",\"https:\\\/\\\/www.instagram.com\\\/pleteninespenko\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"D\u017eemper Dalida | Pletenine \u0160penko","description":"D\u017eemper mornarskog izgleda s patentiranim V izrezom, na rukavima i donjem dijelu. Uzorak pruga u boji upotpunjuje izgled d\u017eempera. Nezamjenjiv u hladnim ljetnim ve\u010derima.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.pleteninespenko.si\/hr\/trgovina\/zenska-pletenina\/zenski-dzemperi\/dzemper-dalida\/","og_locale":"hr_HR","og_type":"article","og_title":"D\u017eemper Dalida | Pletenine \u0160penko","og_description":"D\u017eemper mornarskog izgleda s patentiranim V izrezom, na rukavima i donjem dijelu. Uzorak pruga u boji upotpunjuje izgled d\u017eempera. Nezamjenjiv u hladnim ljetnim ve\u010derima.","og_url":"https:\/\/www.pleteninespenko.si\/hr\/trgovina\/zenska-pletenina\/zenski-dzemperi\/dzemper-dalida\/","og_site_name":"Pletenine \u0160penko","article_publisher":"https:\/\/www.facebook.com\/PletenineSpenko\/","article_modified_time":"2026-09-02T00:10:20+00:00","og_image":[{"width":1200,"height":1324,"url":"https:\/\/www.pleteninespenko.si\/wp-content\/uploads\/2023\/06\/Pletenine_Spenko_pulover-Dalida-bel.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Procijenjeno vrijeme \u010ditanja":"1 minuta"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.pleteninespenko.si\/hr\/trgovina\/zenska-pletenina\/zenski-dzemperi\/dzemper-dalida\/","url":"https:\/\/www.pleteninespenko.si\/hr\/trgovina\/zenska-pletenina\/zenski-dzemperi\/dzemper-dalida\/","name":"D\u017eemper Dalida | Pletenine \u0160penko","isPartOf":{"@id":"https:\/\/www.pleteninespenko.si\/hr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.pleteninespenko.si\/hr\/trgovina\/zenska-pletenina\/zenski-dzemperi\/dzemper-dalida\/#primaryimage"},"image":{"@id":"https:\/\/www.pleteninespenko.si\/hr\/trgovina\/zenska-pletenina\/zenski-dzemperi\/dzemper-dalida\/#primaryimage"},"thumbnailUrl":"https:\/\/www.pleteninespenko.si\/wp-content\/uploads\/2023\/06\/Pletenine_Spenko_pulover-Dalida-bel.jpg","datePublished":"2023-06-02T19:00:58+00:00","dateModified":"2026-09-02T00:10:20+00:00","description":"D\u017eemper mornarskog izgleda s patentiranim V izrezom, na rukavima i donjem dijelu. Uzorak pruga u boji upotpunjuje izgled d\u017eempera. Nezamjenjiv u hladnim ljetnim ve\u010derima.","breadcrumb":{"@id":"https:\/\/www.pleteninespenko.si\/hr\/trgovina\/zenska-pletenina\/zenski-dzemperi\/dzemper-dalida\/#breadcrumb"},"inLanguage":"hr","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.pleteninespenko.si\/hr\/trgovina\/zenska-pletenina\/zenski-dzemperi\/dzemper-dalida\/"]}]},{"@type":"ImageObject","inLanguage":"hr","@id":"https:\/\/www.pleteninespenko.si\/hr\/trgovina\/zenska-pletenina\/zenski-dzemperi\/dzemper-dalida\/#primaryimage","url":"https:\/\/www.pleteninespenko.si\/wp-content\/uploads\/2023\/06\/Pletenine_Spenko_pulover-Dalida-bel.jpg","contentUrl":"https:\/\/www.pleteninespenko.si\/wp-content\/uploads\/2023\/06\/Pletenine_Spenko_pulover-Dalida-bel.jpg","width":1200,"height":1324,"caption":"D\u017eemper mornarskog izgleda s patentiranim V izrezom, na rukavima i donjem dijelu. Uzorak pruga u boji upotpunjuje izgled d\u017eempera. Nezamjenjiv u hladnim ljetnim ve\u010derima."},{"@type":"BreadcrumbList","@id":"https:\/\/www.pleteninespenko.si\/hr\/trgovina\/zenska-pletenina\/zenski-dzemperi\/dzemper-dalida\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.pleteninespenko.si\/hr\/"},{"@type":"ListItem","position":2,"name":"Trgovina","item":"https:\/\/www.pleteninespenko.si\/hr\/trgovina\/"},{"@type":"ListItem","position":3,"name":"D\u017eemper Dalida"}]},{"@type":"WebSite","@id":"https:\/\/www.pleteninespenko.si\/hr\/#website","url":"https:\/\/www.pleteninespenko.si\/hr\/","name":"Pletenine \u0160penko","description":"\u017denska i mu\u0161ka trikota\u017ea po posljednjoj modi","publisher":{"@id":"https:\/\/www.pleteninespenko.si\/hr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.pleteninespenko.si\/hr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"hr"},{"@type":"Organization","@id":"https:\/\/www.pleteninespenko.si\/hr\/#organization","name":"Pletenine \u0160penko","url":"https:\/\/www.pleteninespenko.si\/hr\/","logo":{"@type":"ImageObject","inLanguage":"hr","@id":"https:\/\/www.pleteninespenko.si\/hr\/#\/schema\/logo\/image\/","url":"https:\/\/www.pleteninespenko.si\/wp-content\/uploads\/2020\/06\/Pletenine_Spenko.png","contentUrl":"https:\/\/www.pleteninespenko.si\/wp-content\/uploads\/2020\/06\/Pletenine_Spenko.png","width":717,"height":140,"caption":"Pletenine \u0160penko"},"image":{"@id":"https:\/\/www.pleteninespenko.si\/hr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/PletenineSpenko\/","https:\/\/www.instagram.com\/pleteninespenko\/"]}]}},"brands":[{"id":2137,"name":"Vlastita proizvodnja","slug":"vlastita-proizvodnja"}],"_links":{"self":[{"href":"https:\/\/www.pleteninespenko.si\/hr\/wp-json\/wp\/v2\/product\/28267","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.pleteninespenko.si\/hr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.pleteninespenko.si\/hr\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/www.pleteninespenko.si\/hr\/wp-json\/wp\/v2\/comments?post=28267"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.pleteninespenko.si\/hr\/wp-json\/wp\/v2\/media\/28307"}],"wp:attachment":[{"href":"https:\/\/www.pleteninespenko.si\/hr\/wp-json\/wp\/v2\/media?parent=28267"}],"wp:term":[{"taxonomy":"pwb-brand","embeddable":true,"href":"https:\/\/www.pleteninespenko.si\/hr\/wp-json\/wp\/v2\/pwb-brand?post=28267"},{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.pleteninespenko.si\/hr\/wp-json\/wp\/v2\/product_brand?post=28267"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.pleteninespenko.si\/hr\/wp-json\/wp\/v2\/product_cat?post=28267"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.pleteninespenko.si\/hr\/wp-json\/wp\/v2\/product_tag?post=28267"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}